{"id":667,"date":"2014-09-15T18:48:37","date_gmt":"2014-09-15T18:48:37","guid":{"rendered":"https:\/\/granda.com.br\/?p=667"},"modified":"2016-05-22T23:38:29","modified_gmt":"2016-05-23T02:38:29","slug":"cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/","title":{"rendered":"Cai a exig\u00eancia das certid\u00f5es negativas nas Juntas Comerciais"},"content":{"rendered":"<p><b>Bras\u00edlia, 11\/9\/2014 \u2013\u00a0<\/b>A partir de hoje (11), as empresas est\u00e3o dispensadas de apresentar nas juntas comerciais certid\u00f5es negativas de d\u00e9bitos tribut\u00e1rios, previdenci\u00e1rios e trabalhistas. \u00a0Com isso, elas passam a \u00a0pedir a baixa de seus registros e inscri\u00e7\u00f5es imediatamente ap\u00f3s o encerramento das suas opera\u00e7\u00f5es. Caso sejam identificados d\u00e9bitos tribut\u00e1rios nas empresas encerradas, os s\u00f3cios ser\u00e3o responsabilizados como j\u00e1 previsto na regra atual.<\/p>\n<p>A medida foi estabelecida\u00a0por meio das Instru\u00e7\u00f5es Normativas 25 e 26 do Departamento de Registro Empresarial e Integra\u00e7\u00e3o (DREI)\u00a0da Secretaria da Micro e Pequena Empresa (SMPE). A nova norma \u00e9 baseada na Lei 147\/2014, e tem como objetivo simplificar o registro nas Juntas Comerciais de todo o Brasil.<\/p>\n<p>Al\u00e9m da baixa, as certid\u00f5es n\u00e3o ser\u00e3o mais obrigat\u00f3rias nas opera\u00e7\u00f5es de extin\u00e7\u00e3o, redu\u00e7\u00e3o de capital, cis\u00e3o total ou parcial, incorpora\u00e7\u00e3o, fus\u00e3o transforma\u00e7\u00e3o, transfer\u00eancia do controle de cotas e desmembramento.\u00a0Antes da nova lei, a dispensa de certid\u00f5es para a baixa de empresas somente era garantida ap\u00f3s o prazo de um ano de inatividade.<\/p>\n<p>Para o ministro da Secretaria da Micro e Pequena Empresa, Guilherme Afif Domingos, a medida \u00e9 um grande avan\u00e7o em um Pa\u00eds onde o fechamento de empresas \u00e9 considerado imposs\u00edvel. \u201cTemos cerca de um milh\u00e3o de CNPJs inativos que n\u00e3o s\u00e3o fechados por conta da m\u00e1 burocracia. Sem a exig\u00eancia da certid\u00e3o, vamos encerrar as empresas na hora. Inclusive isso j\u00e1 ser\u00e1 poss\u00edvel no Distrito Federal a partir do dia 25 de setembro. E estamos trabalhando para que essa opera\u00e7\u00e3o se estenda para todo o Brasil o mais breve poss\u00edvel\u201d, destacou.<\/p>\n<p>Em 2013, as Juntas Comerciais processaram mais 1,6 milh\u00e3o de altera\u00e7\u00f5es e 200 mil baixas de empresas. A dispensa de certid\u00f5es diminui a burocracia e reduz custos para os empreendedores, al\u00e9m de agilizar o atendimento das suas demandas pela simplifica\u00e7\u00e3o da an\u00e1lise nos \u00f3rg\u00e3os de registro.<\/p>\n<p><a title=\"\" href=\"http:\/\/drei.smpe.gov.br\/noticias\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/instrucoesnormativasdre25-26.pdf\" target=\"_self\" rel=\"noopener\">Confira aqui a publica\u00e7\u00e3o das portarias 25 e 26 no Di\u00e1rio Oficial da Uni\u00e3o de hoje.<\/a><\/p>\n<p><em>Por Daniel Lansky.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bras\u00edlia, 11\/9\/2014 \u2013\u00a0A partir de hoje (11), as empresas est\u00e3o dispensadas de apresentar nas juntas comerciais certid\u00f5es negativas de d\u00e9bitos tribut\u00e1rios, previdenci\u00e1rios e trabalhistas. \u00a0Com isso, elas passam a \u00a0pedir<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[17,18,19,20,21],"ppma_author":[288],"class_list":["post-667","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-baixa","tag-certidoes-negativas-de-debitos","tag-drei","tag-encerramento-de-empresa","tag-sociedades-limitadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cai a exig\u00eancia das certid\u00f5es negativas nas Juntas Comerciais | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cai a exig\u00eancia das certid\u00f5es negativas nas Juntas Comerciais | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-15T18:48:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-23T02:38:29+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\"},\"headline\":\"Cai a exig\u00eancia das certid\u00f5es negativas nas Juntas Comerciais\",\"datePublished\":\"2014-09-15T18:48:37+00:00\",\"dateModified\":\"2016-05-23T02:38:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\\\/\"},\"wordCount\":370,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"keywords\":[\"Baixa\",\"Certid\u00f5es Negativas de D\u00e9bitos\",\"DREI\",\"Encerramento de empresa\",\"Sociedades Limitadas\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\\\/\",\"name\":\"Cai a exig\u00eancia das certid\u00f5es negativas nas Juntas Comerciais | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2014-09-15T18:48:37+00:00\",\"dateModified\":\"2016-05-23T02:38:29+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cai a exig\u00eancia das certid\u00f5es negativas nas Juntas Comerciais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/granda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cai a exig\u00eancia das certid\u00f5es negativas nas Juntas Comerciais | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/","og_locale":"en_US","og_type":"article","og_title":"Cai a exig\u00eancia das certid\u00f5es negativas nas Juntas Comerciais | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2014-09-15T18:48:37+00:00","article_modified_time":"2016-05-23T02:38:29+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8"},"headline":"Cai a exig\u00eancia das certid\u00f5es negativas nas Juntas Comerciais","datePublished":"2014-09-15T18:48:37+00:00","dateModified":"2016-05-23T02:38:29+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/"},"wordCount":370,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"keywords":["Baixa","Certid\u00f5es Negativas de D\u00e9bitos","DREI","Encerramento de empresa","Sociedades Limitadas"],"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/","url":"https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/","name":"Cai a exig\u00eancia das certid\u00f5es negativas nas Juntas Comerciais | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2014-09-15T18:48:37+00:00","dateModified":"2016-05-23T02:38:29+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/cai-a-exigencia-das-certidoes-negativas-nas-juntas-comerciais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Cai a exig\u00eancia das certid\u00f5es negativas nas Juntas Comerciais"}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161","url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/granda\/"}]}},"authors":[{"term_id":288,"user_id":2,"is_guest":0,"slug":"granda","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=667"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/667\/revisions"}],"predecessor-version":[{"id":887,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/667\/revisions\/887"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=667"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}