{"id":2106,"date":"2024-02-26T09:02:30","date_gmt":"2024-02-26T12:02:30","guid":{"rendered":"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/"},"modified":"2024-02-26T09:02:30","modified_gmt":"2024-02-26T12:02:30","slug":"empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/","title":{"rendered":"Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades"},"content":{"rendered":"<h4>Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades.<\/h4>\n<p>A partir de 1\u00ba de mar\u00e7o as grandes e m\u00e9dias empresas em todo o pa\u00eds ter\u00e3o prazo de 90 dias para realizar o cadastro voluntariamente do novo Domic\u00edlio Judicial Eletr\u00f4nico, criado no Programa Justi\u00e7a 4.0 para centralizar as comunica\u00e7\u00f5es de processos de todos os tribunais brasileiros em uma plataforma digital, conforme prev\u00ea o artigo 246 do CPC e a Resolu\u00e7\u00e3o CNJ n\u00ba 455\/2022.<\/p>\n<p>A introdu\u00e7\u00e3o dessa etapa do Programa foi anunciada no dia 20 de fevereiro de 2024 pelos presidentes do STF e do CNJ, em cerim\u00f4nia realizada para abertura do Ano Judici\u00e1rio do Conselho.<\/p>\n<p>Ap\u00f3s o dia 30 de maio, o cadastro ser\u00e1 feito de forma compuls\u00f3ria de acordo com a base de dados da Receita Federal, sujeito a penalidades e risco de perda de prazos processuais, como por exemplo, a aus\u00eancia de confirma\u00e7\u00e3o do recebimento de cita\u00e7\u00e3o encaminhada ao Domic\u00edlio no prazo legal, sem justificativa, acarretar\u00e1 multa de at\u00e9 5% do valor da causa, por ser considerado ato atentat\u00f3rio \u00e0 dignidade da Justi\u00e7a.<\/p>\n<p>Estima-se que com a implementa\u00e7\u00e3o do sistema os tribunais reduzir\u00e3o em 90% os custos de envio das comunica\u00e7\u00f5es, cita\u00e7\u00f5es e intima\u00e7\u00f5es, atualmente expedidas pelos Correios ou Oficiais de Justi\u00e7a.<\/p>\n<p>A primeira etapa do Programa ocorreu no ano anterior, direcionada apenas aos bancos e institui\u00e7\u00f5es financeiras, com apoio da Federa\u00e7\u00e3o Brasileira de Bancos. Na etapa atual, estima-se que sejam realizados os cadastros de 20 milh\u00f5es de empresas privadas. A pr\u00f3xima etapa est\u00e1 prevista para julho e ir\u00e1 expandir o uso da funcionalidade para todas as institui\u00e7\u00f5es e empresas p\u00fablicas.<\/p>\n<p>O cadastro n\u00e3o \u00e9 obrigat\u00f3rio para pequenas e microempresas que possuem endere\u00e7o eletr\u00f4nico no sistema integrado da Redesim e para pessoas f\u00edsicas, por\u00e9m o CNJ recomenda que todos o fa\u00e7am.<\/p>\n<p>Qualquer d\u00favida sobre o assunto, o nosso time tribut\u00e1rio encontra-se \u00e0 disposi\u00e7\u00e3o para auxiliar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades. A partir de 1\u00ba de mar\u00e7o as grandes e m\u00e9dias empresas em todo o pa\u00eds ter\u00e3o prazo<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42,6],"tags":[],"ppma_author":[287],"class_list":["post-2106","post","type-post","status-publish","format-standard","hentry","category-noticias-en","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-26T12:02:30+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/5efb9715e12b7e1abca8dc93a400379e\"},\"headline\":\"Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades\",\"datePublished\":\"2024-02-26T12:02:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\\\/\"},\"wordCount\":355,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\",\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\\\/\",\"name\":\"Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2024-02-26T12:02:30+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/5efb9715e12b7e1abca8dc93a400379e\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g60fb0f809765fa701e1f037cb4bc32c0\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/g01_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/","og_locale":"en_US","og_type":"article","og_title":"Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2024-02-26T12:02:30+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/5efb9715e12b7e1abca8dc93a400379e"},"headline":"Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades","datePublished":"2024-02-26T12:02:30+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/"},"wordCount":355,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"articleSection":["Not\u00edcias","Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/","url":"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/","name":"Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2024-02-26T12:02:30+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/empresas-tem-90-dias-para-aderir-ao-domicilio-judicial-eletronico-e-evitar-penalidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Empresas t\u00eam 90 dias para aderir ao Domic\u00edlio Judicial Eletr\u00f4nico e evitar penalidades"}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/5efb9715e12b7e1abca8dc93a400379e","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g60fb0f809765fa701e1f037cb4bc32c0","url":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/g01_admin\/"}]}},"authors":[{"term_id":287,"user_id":1,"is_guest":0,"slug":"g01_admin","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/2106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=2106"}],"version-history":[{"count":0,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/2106\/revisions"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=2106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=2106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=2106"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=2106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}