{"id":1956,"date":"2019-11-21T17:24:41","date_gmt":"2019-11-21T20:24:41","guid":{"rendered":"https:\/\/granda.com.br\/?p=1956"},"modified":"2019-11-21T17:24:41","modified_gmt":"2019-11-21T20:24:41","slug":"governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/","title":{"rendered":"Governo do Estado abre novo Programa Especial de Parcelamento do ICMS"},"content":{"rendered":"<h1><strong><span style=\"color: #999999; text-transform: none; text-indent: 0px; letter-spacing: normal; font-family: 'Helvetica Neue',Helvetica,Arial,sans-serif; font-size: 16.87px; font-style: normal; word-spacing: 0px; display: inline !important; white-space: normal; orphans: 2; widows: 2; float: none; -webkit-text-stroke-width: 0px; background-color: #ffffff;\">Redu\u00e7\u00e3o no valor de multas pode chegar at\u00e9 75%; prazo de ades\u00e3o come\u00e7a nesta quinta-feira (7) e vai at\u00e9 15 de dezembro<\/span><\/strong><\/h1>\n<p>&nbsp;<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">O Governo do Estado de S\u00e3o Paulo institui um novo\u00a0<a href=\"https:\/\/www.pepdoicms.sp.gov.br\/pep\/pages\/home\/home.jsf\" target=\"_blank\" rel=\"noopener noreferrer\">Programa Especial de Parcelamento (PEP)<\/a>\u00a0do Imposto sobre a Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os (ICMS). A medida, prevista no Decreto n\u00ba 64.564\/2019, publicado nesta quarta-feira (6) no Di\u00e1rio Oficial do Estado, permite que os contribuintes paulistas regularizem suas d\u00edvidas relativas a esse tributo.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">Os contribuintes que aderirem ao PEP contar\u00e3o com redu\u00e7\u00e3o de 75% no valor das multas e de 60% nos juros, no caso de pagamentos \u00e0 vista. Para pagamentos parcelados em at\u00e9 60 meses, o desconto ser\u00e1 de 50% no valor das multas e de 40% nos juros. No caso do pagamento parcelado, o valor m\u00ednimo de cada parcela deve ser de R$ 500, incidindo acr\u00e9scimos financeiros de 0,64% a.m. para liquida\u00e7\u00e3o em at\u00e9 12 parcelas; 0,80% a.m. para liquida\u00e7\u00e3o entre 13 e 30 parcelas; e 1% a.m. para liquida\u00e7\u00e3o entre 31 e 60 parcelas.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">O prazo de ades\u00e3o ao programa come\u00e7a nesta quinta-feira (7) e vai at\u00e9 15 de dezembro. O PEP permite a quita\u00e7\u00e3o ou o parcelamento de d\u00e9bitos de ICMS, inscritos ou n\u00e3o em d\u00edvida ativa, inclusive os que s\u00e3o objeto de questionamentos judiciais, em raz\u00e3o de fatos geradores ocorridos at\u00e9 31 de maio de 2019.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">Para aderir, o contribuinte deve acessar o site\u00a0<a href=\"https:\/\/www.pepdoicms.sp.gov.br\/pep\/pages\/home\/home.jsf\" target=\"_blank\" rel=\"noopener noreferrer\">www.pepdoicms.sp.gov.br<\/a>, efetuar o login no sistema com a mesma senha de acesso utilizada no Posto Fiscal Eletr\u00f4nico (PFE) e selecionar os d\u00e9bitos tribut\u00e1rios a serem inclu\u00eddos no programa.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">A abertura do PEP j\u00e1 havia sido autorizada pelo Conselho nacional de Pol\u00edtica Fazend\u00e1ria (Confaz), por meio do Conv\u00eanio ICMS n\u00ba 152\/2019.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\"><strong>Regulariza\u00e7\u00e3o e Recupera\u00e7\u00e3o<\/strong><\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">\u201cO programa \u00e9 uma oportunidade de regulariza\u00e7\u00e3o para contribuintes que s\u00e3o cumpridores de suas obriga\u00e7\u00f5es fiscais, mas que, em raz\u00e3o de fatores como a crise econ\u00f4mica, tiveram suas atividades prejudicadas\u201d, afirma o Secret\u00e1rio de Fazenda e Planejamento do Estado de S\u00e3o Paulo, Henrique Meirelles.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">Ao aderirem ao PEP, desde que mantendo os pagamentos da renegocia\u00e7\u00e3o em dia, as empresas voltam a gozar de regularidade junto ao fisco estadual, o que reestabelece suas capacidades de participar de licita\u00e7\u00f5es p\u00fablicas e de acessar financiamentos.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">\u201cA economia paulista est\u00e1 crescendo mais que a m\u00e9dia nacional, ent\u00e3o entendemos que restabelecer a regularidade das nossas empresas \u00e9 importante tamb\u00e9m para que elas recuperem, mais rapidamente, sua capacidade plena de funcionamento e contribuam para o aumento do emprego e da renda de S\u00e3o Paulo\u201d, destaca o Secret\u00e1rio.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\"><strong>Arrecada\u00e7\u00e3o<\/strong><\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">A expectativa do Governo do Estado com o programa \u00e9 arrecadar cerca de R$ 3,1 bilh\u00f5es, dos quais aproximadamente R$ 650 milh\u00f5es ainda em 2019. Para as ades\u00f5es realizadas entre 7 e 15 de novembro, o vencimento da primeira parcela ou da parcela \u00fanica ser\u00e1 em 25 de novembro. J\u00e1 no caso das ades\u00f5es efetuadas do dia 16 ao \u00faltimo dia do m\u00eas, o vencimento ser\u00e1 no dia 10 de dezembro. As ades\u00f5es feitas entre 1\u00ba e 15 de dezembro ter\u00e3o vencimento em 20 de dezembro. As demais parcelas dever\u00e3o ser quitadas nos meses subsequentes, com vencimento a depender da data de ades\u00e3o do contribuinte.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">O Coordenador da Administra\u00e7\u00e3o Tribut\u00e1ria da Secretaria da Fazenda e Planejamento, Gustavo Ley, explica que uma s\u00e9rie de medidas t\u00eam contribu\u00eddo para a redu\u00e7\u00e3o das taxas de inadimpl\u00eancia, como a possibilidade de autorregulariza\u00e7\u00e3o dos contribuintes e os servi\u00e7os de telemarketing que buscam os contribuintes. Mas ele destaca que programas de recupera\u00e7\u00e3o fiscal s\u00e3o importantes por impedirem o agravamento da situa\u00e7\u00e3o de contribuintes em d\u00e9bito.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">\u201cA ades\u00e3o ao programa de parcelamento, com o adequado cumprimento das regras que ele prev\u00ea, regulariza o relacionamento das empresas com o fisco estadual e contribui para que elas mantenham suas contas em ordem\u201d, explica Ley.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\"><strong>Casos Especiais<\/strong><\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">O programa tem regras espec\u00edficas para contribuintes que t\u00eam d\u00e9bitos relativos a autos de infra\u00e7\u00e3o e multas que ainda n\u00e3o tenham sido inscritos na d\u00edvida ativa. Para os d\u00e9bitos exigidos por meio de auto de infra\u00e7\u00e3o ainda n\u00e3o inscritos em d\u00edvida ativa, est\u00e3o previstas redu\u00e7\u00f5es adicionais e cumulativas no valor da multa correspondentes a 70% se o objeto da ades\u00e3o ocorrer em at\u00e9 15 dias a partir da notifica\u00e7\u00e3o, 60% se ocorrer no per\u00edodo de 16 a 30 dias da lavratura do auto e 25% nos demais casos.<\/p>\n<p style=\"box-sizing: inherit; color: #333333; font-size: 1.125em; line-height: 1.5 !important; margin: 0px 0px 30px; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-style: initial; text-decoration-color: initial;\">No caso de d\u00e9bitos fiscais decorrentes de substitui\u00e7\u00e3o tribut\u00e1ria, o parcelamento \u00e9 permitido em at\u00e9 seis meses, com incid\u00eancia de acr\u00e9scimos financeiros de 0,64% ao m\u00eas, com os mesmos descontos.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: <a href=\"http:\/\/www.saopaulo.sp.gov.br\/spnoticias\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/\" target=\"_blank\" rel=\"noopener\">Governo do Estado de S\u00e3o Paulo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redu\u00e7\u00e3o no valor de multas pode chegar at\u00e9 75%; prazo de ades\u00e3o come\u00e7a nesta quinta-feira (7) e vai at\u00e9 15 de dezembro &nbsp; O Governo do Estado de S\u00e3o Paulo<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[9,10,230,212],"ppma_author":[288],"class_list":["post-1956","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-icms","tag-parcelamento","tag-parcelamento-especial","tag-sao-paulo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo do Estado abre novo Programa Especial de Parcelamento do ICMS | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo do Estado abre novo Programa Especial de Parcelamento do ICMS | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-21T20:24:41+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\"},\"headline\":\"Governo do Estado abre novo Programa Especial de Parcelamento do ICMS\",\"datePublished\":\"2019-11-21T20:24:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\\\/\"},\"wordCount\":814,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"keywords\":[\"ICMS\",\"Parcelamento\",\"parcelamento especial\",\"s\u00e3o paulo\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\\\/\",\"name\":\"Governo do Estado abre novo Programa Especial de Parcelamento do ICMS | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2019-11-21T20:24:41+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo do Estado abre novo Programa Especial de Parcelamento do ICMS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/granda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo do Estado abre novo Programa Especial de Parcelamento do ICMS | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/","og_locale":"en_US","og_type":"article","og_title":"Governo do Estado abre novo Programa Especial de Parcelamento do ICMS | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2019-11-21T20:24:41+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8"},"headline":"Governo do Estado abre novo Programa Especial de Parcelamento do ICMS","datePublished":"2019-11-21T20:24:41+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/"},"wordCount":814,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"keywords":["ICMS","Parcelamento","parcelamento especial","s\u00e3o paulo"],"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/","url":"https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/","name":"Governo do Estado abre novo Programa Especial de Parcelamento do ICMS | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2019-11-21T20:24:41+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/governo-do-estado-abre-novo-programa-especial-de-parcelamento-do-icms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Governo do Estado abre novo Programa Especial de Parcelamento do ICMS"}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161","url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/granda\/"}]}},"authors":[{"term_id":288,"user_id":2,"is_guest":0,"slug":"granda","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=1956"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1956\/revisions"}],"predecessor-version":[{"id":1957,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1956\/revisions\/1957"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=1956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=1956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=1956"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=1956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}