{"id":1921,"date":"2018-10-21T17:39:13","date_gmt":"2018-10-21T20:39:13","guid":{"rendered":"https:\/\/granda.com.br\/?p=1921"},"modified":"2018-10-21T17:39:13","modified_gmt":"2018-10-21T20:39:13","slug":"creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/","title":{"rendered":"Cr\u00e9ditos de PIS\/COFINS: PGFN emite Nota Explicativa autorizando a dispensa de recursos."},"content":{"rendered":"<p>Considerando a pacifica\u00e7\u00e3o pelo Superior Tribunal de Justi\u00e7a (STJ) da tem\u00e1tica do conceito de insumo para fins de creditamento do PIS e da COFINS n\u00e3o cumulativos, a Procuradoria Geral da Fazenda Nacional (PGFN) publicou a Nota Explicativa n\u00ba. 63 autorizando a dispensa de contesta\u00e7\u00e3o e de interposi\u00e7\u00e3o de recursos em processos judiciais que versem sobre a aplica\u00e7\u00e3o restritiva prevista nas Instru\u00e7\u00f5es Normativas SRF n\u00ba 247\/2002 e 404\/2004, julgadas ilegais pelo STJ.<\/p>\n<p>Segundo a Nota, tanto o Procurador da Fazenda Nacional como o Auditor-Fiscal, que atuam nos processos nos quais se questiona o enquadramento de determinado item como insumo para fins da n\u00e3o-cumulatividade do PIS e da COFINS, dever\u00e3o adotar o conceito de insumos definido pelo STJ, mas n\u00e3o est\u00e3o obrigados a, necessariamente, aceitar o enquadramento do item questionado como insumo, devendo-se verificar se o item discutido se amolda ou n\u00e3o na nova conceitua\u00e7\u00e3o decorrente do julgamento do STJ.<\/p>\n<p>A esse respeito, conforme j\u00e1 amplamente divulgado, o STJ assentou recentemente as seguintes teses: \u201c(a) \u00e9 ilegal a disciplina de creditamento prevista nas Instru\u00e7\u00f5es Normativas da SRF ns. 247\/2002 e 404\/2004, porquanto compromete a efic\u00e1cia do sistema de n\u00e3o-cumulatividade da contribui\u00e7\u00e3o ao PIS e da COFINS, tal como definido nas Lei n\u00ba 10.637\/2002 e 10.833\/2003; e (b) o conceito de insumo deve ser aferido \u00e0 luz dos crit\u00e9rios de essencialidade ou relev\u00e2ncia, ou seja, considerando-se a imprescindibilidade ou a import\u00e2ncia de determinado item \u2013 bem ou servi\u00e7o \u2013 para o desenvolvimento da atividade econ\u00f4mica desempenhada pelo Contribuinte.\u201d<\/p>\n<p>Ainda no \u00e2mbito da Nota Explicativa, a PGFN sugere a aplica\u00e7\u00e3o do \u201cteste de subtra\u00e7\u00e3o\u201d (mencionado no voto do Ministro Mauro Campbell) como instrumento \u00fatil para a compreens\u00e3o do conceito de insumos, ainda que observe expressamente que tal m\u00e9todo n\u00e3o esteja na tese firmada.<\/p>\n<p>Todavia, o voto vencedor do Ministro Napole\u00e3o Nunes Maia Filho, ao consignar a orienta\u00e7\u00e3o constante do voto da Ministra Regina Helena Costa, afastou a aplica\u00e7\u00e3o do aludido \u201cteste de subtra\u00e7\u00e3o\u201d, que prestigia a avalia\u00e7\u00e3o dos crit\u00e9rios de essencialidade e pertin\u00eancia, para fixar que o conceito de insumo deve ser aferido \u00e0 luz dos crit\u00e9rios de essencialidade ou relev\u00e2ncia.<\/p>\n<p>No que concerne ao conceito de relev\u00e2ncia, a Ministra Regina Helena Costa esclarece que tal crit\u00e9rio definidor de insumo \u00e9 identific\u00e1vel no item cuja a finalidade, embora n\u00e3o indispens\u00e1vel \u00e0 elabora\u00e7\u00e3o do pr\u00f3prio produto ou \u00e0 presta\u00e7\u00e3o do servi\u00e7o, integre o processo de produ\u00e7\u00e3o, seja pelas singularidades de cada cadeia produtiva, seja por imposi\u00e7\u00e3o legal, distanciando-se, nesta medida, da acep\u00e7\u00e3o de pertin\u00eancia, pelo emprego na produ\u00e7\u00e3o ou na execu\u00e7\u00e3o dos servi\u00e7os.<\/p>\n<p>Desse modo, sob a perspectiva do voto vencedor, o crit\u00e9rio da relev\u00e2ncia revela-se mais abrangente do que o da pertin\u00eancia.<\/p>\n<p>Ademais, se por um lado foram afastados os crit\u00e9rios mais restritivos contidos nas Instru\u00e7\u00f5es Normativas SRF n\u00ba 247\/2002 e 404\/2004, foram igualmente repelidos os crit\u00e9rios utilizados para fins de apura\u00e7\u00e3o de Imposto de Renda das Pessoas Jur\u00eddicas, que correspondem aos conceitos de \u201ccustos e despesas operacionais\u201d, o que vale dizer \u00e9 que n\u00e3o ser\u00e3o todas as despesas da atividade empresarial que ser\u00e3o considerados como insumos.<\/p>\n<p>Este \u00e9 um importante momento para que os Contribuintes analisem, cuidadosamente, sob a nova \u00f3tica do STJ, a possibilidade de ampliar a base de cr\u00e9ditos de PIS e COFINS na sistem\u00e1tica n\u00e3o cumulativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Considerando a pacifica\u00e7\u00e3o pelo Superior Tribunal de Justi\u00e7a (STJ) da tem\u00e1tica do conceito de insumo para fins de creditamento do PIS e da COFINS n\u00e3o cumulativos, a Procuradoria Geral da<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"ppma_author":[287],"class_list":["post-1921","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cr\u00e9ditos de PIS\/COFINS: PGFN emite Nota Explicativa autorizando a dispensa de recursos. | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cr\u00e9ditos de PIS\/COFINS: PGFN emite Nota Explicativa autorizando a dispensa de recursos. | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-21T20:39:13+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/5efb9715e12b7e1abca8dc93a400379e\"},\"headline\":\"Cr\u00e9ditos de PIS\\\/COFINS: PGFN emite Nota Explicativa autorizando a dispensa de recursos.\",\"datePublished\":\"2018-10-21T20:39:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\\\/\"},\"wordCount\":598,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\\\/\",\"name\":\"Cr\u00e9ditos de PIS\\\/COFINS: PGFN emite Nota Explicativa autorizando a dispensa de recursos. | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2018-10-21T20:39:13+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cr\u00e9ditos de PIS\\\/COFINS: PGFN emite Nota Explicativa autorizando a dispensa de recursos.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/5efb9715e12b7e1abca8dc93a400379e\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g60fb0f809765fa701e1f037cb4bc32c0\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/g01_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cr\u00e9ditos de PIS\/COFINS: PGFN emite Nota Explicativa autorizando a dispensa de recursos. | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/","og_locale":"en_US","og_type":"article","og_title":"Cr\u00e9ditos de PIS\/COFINS: PGFN emite Nota Explicativa autorizando a dispensa de recursos. | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2018-10-21T20:39:13+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/5efb9715e12b7e1abca8dc93a400379e"},"headline":"Cr\u00e9ditos de PIS\/COFINS: PGFN emite Nota Explicativa autorizando a dispensa de recursos.","datePublished":"2018-10-21T20:39:13+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/"},"wordCount":598,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/","url":"https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/","name":"Cr\u00e9ditos de PIS\/COFINS: PGFN emite Nota Explicativa autorizando a dispensa de recursos. | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2018-10-21T20:39:13+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/creditos-de-pis-cofins-pgfn-emite-nota-explicativa-autorizando-a-dispensa-de-recursos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Cr\u00e9ditos de PIS\/COFINS: PGFN emite Nota Explicativa autorizando a dispensa de recursos."}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/5efb9715e12b7e1abca8dc93a400379e","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g60fb0f809765fa701e1f037cb4bc32c0","url":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/g01_admin\/"}]}},"authors":[{"term_id":287,"user_id":1,"is_guest":0,"slug":"g01_admin","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=1921"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1921\/revisions"}],"predecessor-version":[{"id":1922,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1921\/revisions\/1922"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=1921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=1921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=1921"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=1921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}