{"id":1865,"date":"2018-06-12T11:42:56","date_gmt":"2018-06-12T14:42:56","guid":{"rendered":"https:\/\/granda.com.br\/en\/alteracoes-nas-regras-de-compensacao-tributaria\/"},"modified":"2018-06-12T11:44:17","modified_gmt":"2018-06-12T14:44:17","slug":"alteracoes-nas-regras-de-compensacao-tributaria","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/alteracoes-nas-regras-de-compensacao-tributaria\/","title":{"rendered":"Altera\u00e7\u00f5es nas regras de compensa\u00e7\u00e3o tribut\u00e1ria."},"content":{"rendered":"<p>O Governo Federal promoveu altera\u00e7\u00e3o no artigo 74 da Lei 9.430\/96, que disp\u00f5e sobre as regras de compensa\u00e7\u00e3o tribut\u00e1ria. A referida altera\u00e7\u00e3o foi inserida no contexto da Lei 13.670\/18, que trata da reonera\u00e7\u00e3o a folha de pagamento para alguns setores.<\/p>\n<p>De acordo com a nova regra de compensa\u00e7\u00e3o, as empresas que apuram pelo Lucro Real e possuem cr\u00e9ditos tribut\u00e1rios, inclusive oriundos de a\u00e7\u00e3o judicial, n\u00e3o poder\u00e3o utiliz\u00e1-los para pagamento de d\u00e9bitos relativos ao recolhimento mensal por estimativa do Imposto sobre a Renda das Pessoas Jur\u00eddicas (IRPJ) e da Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido (CSLL).<\/p>\n<p>Essa altera\u00e7\u00e3o passa a vigorar a partir de junho de 2018, prejudicando o fluxo de caixa de muitas empresas que contavam com a possibilidade dessas compensa\u00e7\u00f5es, devendo, agora, desembolsar dinheiro para recolhimento dos referidos tributos.<\/p>\n<p>Com a nova regra em vigor, as empresas que optaram pelo Lucro Real Anual ainda poder\u00e3o utilizar seus cr\u00e9ditos tribut\u00e1rios para pagamento de outros tributos federais, como o PIS e a COFINS.<\/p>\n<p>As empresas prejudicadas com a nova regra poder\u00e3o ingressar com medida judicial visando assegurar seu direito \u00e0 compensa\u00e7\u00e3o, tendo em vista que a altera\u00e7\u00e3o na legisla\u00e7\u00e3o ocorreu no meio do ano calend\u00e1rio, ferindo princ\u00edpios como o da seguran\u00e7a jur\u00eddica, a n\u00e3o surpresa e a prote\u00e7\u00e3o a confian\u00e7a.<\/p>\n<p>Outra altera\u00e7\u00e3o importante \u00e9 a possibilidade das empresas que apuram, por meio do eSocial, as Contribui\u00e7\u00f5es Previdenci\u00e1rias previstas nas al\u00edneas a, b e c do par\u00e1grafo \u00fanico do artigo 11\u00ba da Lei 8.212\/91, a compensarem as referidas contribui\u00e7\u00f5es com cr\u00e9ditos dos demais tributos administrados pela Receita Federal do Brasil, relativos aos per\u00edodos de apura\u00e7\u00e3o posteriores \u00e0 utiliza\u00e7\u00e3o do eSocial. A Receita Federal ainda disciplinar\u00e1 a esse respeito.<\/p>\n<p>As empresas que n\u00e3o utilizam o eSocial n\u00e3o poder\u00e3o se beneficiar da compensa\u00e7\u00e3o das contribui\u00e7\u00f5es previdenci\u00e1rias com os demais tributos administrados pela Receita Federal. Igualmente n\u00e3o ser\u00e1 permitida, nesse contexto, a compensa\u00e7\u00e3o de tributos relativos aos per\u00edodos de apura\u00e7\u00e3o anteriores \u00e0 utiliza\u00e7\u00e3o do eSocial.<\/p>\n<p>Ficamos \u00e0 disposi\u00e7\u00e3o para maiores esclarecimentos!<\/p>\n<p>Atenciosamente,<\/p>\n<p>Gabriela Semeghini<\/p>\n<p>Luana Oliveira<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo Federal promoveu altera\u00e7\u00e3o no artigo 74 da Lei 9.430\/96, que disp\u00f5e sobre as regras de compensa\u00e7\u00e3o tribut\u00e1ria. A referida altera\u00e7\u00e3o foi inserida no contexto da Lei 13.670\/18, que<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"ppma_author":[287],"class_list":["post-1865","post","type-post","status-publish","format-standard","hentry","category-noticias-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Altera\u00e7\u00f5es nas regras de compensa\u00e7\u00e3o tribut\u00e1ria. | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Altera\u00e7\u00f5es nas regras de compensa\u00e7\u00e3o tribut\u00e1ria. | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-12T14:42:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-12T14:44:17+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/alteracoes-nas-regras-de-compensacao-tributaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/alteracoes-nas-regras-de-compensacao-tributaria\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/5efb9715e12b7e1abca8dc93a400379e\"},\"headline\":\"Altera\u00e7\u00f5es nas regras de compensa\u00e7\u00e3o tribut\u00e1ria.\",\"datePublished\":\"2018-06-12T14:42:56+00:00\",\"dateModified\":\"2018-06-12T14:44:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/alteracoes-nas-regras-de-compensacao-tributaria\\\/\"},\"wordCount\":384,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/alteracoes-nas-regras-de-compensacao-tributaria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/alteracoes-nas-regras-de-compensacao-tributaria\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/alteracoes-nas-regras-de-compensacao-tributaria\\\/\",\"name\":\"Altera\u00e7\u00f5es nas regras de compensa\u00e7\u00e3o tribut\u00e1ria. | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2018-06-12T14:42:56+00:00\",\"dateModified\":\"2018-06-12T14:44:17+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/alteracoes-nas-regras-de-compensacao-tributaria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/alteracoes-nas-regras-de-compensacao-tributaria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/alteracoes-nas-regras-de-compensacao-tributaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Altera\u00e7\u00f5es nas regras de compensa\u00e7\u00e3o tribut\u00e1ria.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/5efb9715e12b7e1abca8dc93a400379e\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g60fb0f809765fa701e1f037cb4bc32c0\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/g01_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Altera\u00e7\u00f5es nas regras de compensa\u00e7\u00e3o tribut\u00e1ria. | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/","og_locale":"en_US","og_type":"article","og_title":"Altera\u00e7\u00f5es nas regras de compensa\u00e7\u00e3o tribut\u00e1ria. | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2018-06-12T14:42:56+00:00","article_modified_time":"2018-06-12T14:44:17+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/5efb9715e12b7e1abca8dc93a400379e"},"headline":"Altera\u00e7\u00f5es nas regras de compensa\u00e7\u00e3o tribut\u00e1ria.","datePublished":"2018-06-12T14:42:56+00:00","dateModified":"2018-06-12T14:44:17+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/"},"wordCount":384,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/","url":"https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/","name":"Altera\u00e7\u00f5es nas regras de compensa\u00e7\u00e3o tribut\u00e1ria. | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2018-06-12T14:42:56+00:00","dateModified":"2018-06-12T14:44:17+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/alteracoes-nas-regras-de-compensacao-tributaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Altera\u00e7\u00f5es nas regras de compensa\u00e7\u00e3o tribut\u00e1ria."}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/5efb9715e12b7e1abca8dc93a400379e","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g60fb0f809765fa701e1f037cb4bc32c0","url":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/g01_admin\/"}]}},"authors":[{"term_id":287,"user_id":1,"is_guest":0,"slug":"g01_admin","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/231bda61c939e3026c07204d045a5f9206b906b90e97e8d717bc8a2afc5c887c?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=1865"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1865\/revisions"}],"predecessor-version":[{"id":1866,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1865\/revisions\/1866"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=1865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=1865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=1865"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=1865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}