{"id":1820,"date":"2018-02-06T10:33:37","date_gmt":"2018-02-06T12:33:37","guid":{"rendered":"https:\/\/granda.com.br\/?p=1820"},"modified":"2018-02-06T10:33:37","modified_gmt":"2018-02-06T12:33:37","slug":"consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/","title":{"rendered":"Consolida\u00e7\u00e3o PGFN &#8211; Reabertura do REFIS da Crise &#8211; Portaria n\u00ba 31, de 02 de fevereiro de 2018"},"content":{"rendered":"<p>A Procuradoria Geral da Fazenda Nacional publicou ontem, dia 5 de fevereiro, a Portaria 31\/2018 que disp\u00f5e sobre os procedimentos relativos \u00e0 <strong>consolida\u00e7\u00e3o<\/strong> de d\u00e9bitos para parcelamento e pagamento \u00e0 vista com utiliza\u00e7\u00e3o de cr\u00e9ditos decorrentes de preju\u00edzo fiscal ou de base de c\u00e1lculo negativa da Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido (CSLL) de que trata o art. 17 da Lei n\u00ba 12.865, de 9 de outubro de 2013 (Reabertura do REFIS), no \u00e2mbito da Procuradoria-Geral da Fazenda Nacional (PGFN).<\/p>\n<p>Na consolida\u00e7\u00e3o o contribuinte dever\u00e1 indicar:<\/p>\n<p>I &#8211; os d\u00e9bitos a serem parcelados;<\/p>\n<p>II &#8211; o n\u00famero de presta\u00e7\u00f5es pretendidas; e<\/p>\n<p>III &#8211; os montantes de cr\u00e9ditos decorrentes de preju\u00edzo fiscal e de base de c\u00e1lculo negativa da CSLL a serem utilizados para liquida\u00e7\u00e3o de valores correspondentes a multas, de mora ou de of\u00edcio, e a juros morat\u00f3rios.<\/p>\n<p><strong>O prazo para a consolida\u00e7\u00e3o \u00e9 do dia 6 a 28 de fevereiro de 2018.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Ficamos \u00e0 disposi\u00e7\u00e3o!<\/p>\n<p>Atenciosamente,<\/p>\n<p>Granda Advogados<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Procuradoria Geral da Fazenda Nacional publicou ontem, dia 5 de fevereiro, a Portaria 31\/2018 que disp\u00f5e sobre os procedimentos relativos \u00e0 consolida\u00e7\u00e3o de d\u00e9bitos para parcelamento e pagamento \u00e0<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[90,238,8],"ppma_author":[288],"class_list":["post-1820","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-consolidacao","tag-pgfn","tag-refis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consolida\u00e7\u00e3o PGFN - Reabertura do REFIS da Crise - Portaria n\u00ba 31, de 02 de fevereiro de 2018 | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consolida\u00e7\u00e3o PGFN - Reabertura do REFIS da Crise - Portaria n\u00ba 31, de 02 de fevereiro de 2018 | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-06T12:33:37+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\"},\"headline\":\"Consolida\u00e7\u00e3o PGFN &#8211; Reabertura do REFIS da Crise &#8211; Portaria n\u00ba 31, de 02 de fevereiro de 2018\",\"datePublished\":\"2018-02-06T12:33:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\\\/\"},\"wordCount\":184,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"keywords\":[\"Consolida\u00e7\u00e3o\",\"PGFN\",\"REFIS\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\\\/\",\"name\":\"Consolida\u00e7\u00e3o PGFN - Reabertura do REFIS da Crise - Portaria n\u00ba 31, de 02 de fevereiro de 2018 | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2018-02-06T12:33:37+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consolida\u00e7\u00e3o PGFN &#8211; Reabertura do REFIS da Crise &#8211; Portaria n\u00ba 31, de 02 de fevereiro de 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/granda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consolida\u00e7\u00e3o PGFN - Reabertura do REFIS da Crise - Portaria n\u00ba 31, de 02 de fevereiro de 2018 | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/","og_locale":"en_US","og_type":"article","og_title":"Consolida\u00e7\u00e3o PGFN - Reabertura do REFIS da Crise - Portaria n\u00ba 31, de 02 de fevereiro de 2018 | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2018-02-06T12:33:37+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8"},"headline":"Consolida\u00e7\u00e3o PGFN &#8211; Reabertura do REFIS da Crise &#8211; Portaria n\u00ba 31, de 02 de fevereiro de 2018","datePublished":"2018-02-06T12:33:37+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/"},"wordCount":184,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"keywords":["Consolida\u00e7\u00e3o","PGFN","REFIS"],"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/","url":"https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/","name":"Consolida\u00e7\u00e3o PGFN - Reabertura do REFIS da Crise - Portaria n\u00ba 31, de 02 de fevereiro de 2018 | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2018-02-06T12:33:37+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/consolidacao-pgfn-reabertura-do-refis-da-crise-portaria-no-31-de-02-de-fevereiro-de-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Consolida\u00e7\u00e3o PGFN &#8211; Reabertura do REFIS da Crise &#8211; Portaria n\u00ba 31, de 02 de fevereiro de 2018"}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161","url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/granda\/"}]}},"authors":[{"term_id":288,"user_id":2,"is_guest":0,"slug":"granda","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=1820"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1820\/revisions"}],"predecessor-version":[{"id":1821,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1820\/revisions\/1821"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=1820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=1820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=1820"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=1820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}