{"id":1811,"date":"2018-01-12T14:29:55","date_gmt":"2018-01-12T16:29:55","guid":{"rendered":"https:\/\/granda.com.br\/en\/?p=1811"},"modified":"2018-01-12T14:29:55","modified_gmt":"2018-01-12T16:29:55","slug":"repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/","title":{"rendered":"Repetitivo vai definir legalidade do ICMS sobre Tust e Tusd"},"content":{"rendered":"<p><span style=\"color: #000000;\">A legalidade da inclus\u00e3o da Tarifa de Uso do Sistema de Transmiss\u00e3o (Tust) e da Tarifa de Uso do Sistema de Distribui\u00e7\u00e3o (Tusd) de energia el\u00e9trica na base de c\u00e1lculo do Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os (ICMS) ser\u00e1 definida pela Primeira Se\u00e7\u00e3o do Superior Tribunal de Justi\u00e7a (STJ), em julgamento submetido ao rito dos recursos repetitivos.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">A se\u00e7\u00e3o decidiu que ser\u00e3o julgados como repetitivos tr\u00eas recursos sobre o tema: o REsp 1.692.023, o REsp 1.699.851 e o EREsp 1.163.020. A proposta de afeta\u00e7\u00e3o foi apresentada pelo ministro Herman Benjamin, que tamb\u00e9m determinou a suspens\u00e3o em todo o territ\u00f3rio nacional dos processos pendentes, individuais ou coletivos, que versem sobre a quest\u00e3o.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">Mat\u00e9ria controversa\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">Em mar\u00e7o de 2017, a Primeira Turma do STJ decidiu pela legalidade do ICMS na Tusd, cobrada nas contas de grandes consumidores que adquirem a energia el\u00e9trica diretamente das empresas geradoras. Por maioria, a turma entendeu que \u00e9 imposs\u00edvel separar a atividade de transmiss\u00e3o ou distribui\u00e7\u00e3o de energia das demais, j\u00e1 que ela \u00e9 gerada, transmitida, distribu\u00edda e consumida simultaneamente.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">O relator da mat\u00e9ria, ministro Gurgel de Faria, foi acompanhado pelos ministros Benedito Gon\u00e7alves e S\u00e9rgio Kukina. Os ministros Napole\u00e3o Nunes Maia Filho e Regina Helena Costa ficaram vencidos.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">Ap\u00f3s o julgamento, a parte recorrente ingressou com embargos de diverg\u00eancia na Corte Especial. O pedido foi indeferido liminarmente e redistribu\u00eddo \u00e0 Primeira Se\u00e7\u00e3o, colegiado que re\u00fane os dez ministros da Primeira e da Segunda Turma do STJ, ambas especializadas em direito p\u00fablico.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">Ao analisar a controv\u00e9rsia, o relator do caso na Primeira Se\u00e7\u00e3o, Herman Benjamin, destacou a relev\u00e2ncia da mat\u00e9ria para o or\u00e7amento dos estados, justificando o julgamento sob o rito dos recursos repetitivos para definir a tese a ser aplicada nesses casos.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">O relator frisou que \u201ca Tusd e a Tust s\u00e3o tarifas que t\u00eam como suporte jur\u00eddico o mesmo dispositivo legal\u201d, o que explica o julgamento conjunto dos tr\u00eas recursos elencados. A proposta de afeta\u00e7\u00e3o foi aprovada por maioria.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">O tema est\u00e1 cadastrado sob o n\u00famero 986 e pode ser acompanhado na p\u00e1gina de repetitivos do STJ.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">Recursos repetitivos\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">O C\u00f3digo de Processo Civil de 2015 regula nos artigos 1.036 a 1.041 o julgamento por amostragem, mediante a sele\u00e7\u00e3o de recursos especiais que tenham controv\u00e9rsias id\u00eanticas. Conforme previsto nos artigos 121-A do Regimento Interno do STJ e 927 do CPC, a defini\u00e7\u00e3o da tese pelo STJ vai servir de orienta\u00e7\u00e3o \u00e0s inst\u00e2ncias ordin\u00e1rias da Justi\u00e7a, inclusive aos juizados especiais, para a solu\u00e7\u00e3o de casos fundados na mesma controv\u00e9rsia.\u00a0<\/span><br \/>\n<span style=\"color: #000000;\">A tese estabelecida em repetitivo tamb\u00e9m ter\u00e1 importante reflexo na admissibilidade de recursos para o STJ e em outras situa\u00e7\u00f5es processuais, como a tutela da evid\u00eancia (artigo 311, II, do CPC) e a improced\u00eancia liminar do pedido (artigo 332 do CPC).\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">REsp 1692023\u2022 REsp 1699851\u2022 EREsp 1163020<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: <a href=\"http:\/\/www.stj.jus.br\/sites\/STJ\/default\/pt_BR\/Comunica%C3%A7%C3%A3o\/noticias\/Not%C3%ADcias\/Repetitivo-vai-definir-legalidade-do-ICMS-sobre-Tust-e-Tusd\" target=\"_blank\" rel=\"noopener\">Superior Tribunal de Justi\u00e7a<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A legalidade da inclus\u00e3o da Tarifa de Uso do Sistema de Transmiss\u00e3o (Tust) e da Tarifa de Uso do Sistema de Distribui\u00e7\u00e3o (Tusd) de energia el\u00e9trica na base de c\u00e1lculo<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[61],"ppma_author":[288],"class_list":["post-1811","post","type-post","status-publish","format-standard","hentry","category-noticias-en","tag-tributario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Repetitivo vai definir legalidade do ICMS sobre Tust e Tusd | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Repetitivo vai definir legalidade do ICMS sobre Tust e Tusd | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-12T16:29:55+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\"},\"headline\":\"Repetitivo vai definir legalidade do ICMS sobre Tust e Tusd\",\"datePublished\":\"2018-01-12T16:29:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\\\/\"},\"wordCount\":523,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"keywords\":[\"Tribut\u00e1rio\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\\\/\",\"name\":\"Repetitivo vai definir legalidade do ICMS sobre Tust e Tusd | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2018-01-12T16:29:55+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Repetitivo vai definir legalidade do ICMS sobre Tust e Tusd\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/granda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Repetitivo vai definir legalidade do ICMS sobre Tust e Tusd | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/","og_locale":"en_US","og_type":"article","og_title":"Repetitivo vai definir legalidade do ICMS sobre Tust e Tusd | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2018-01-12T16:29:55+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8"},"headline":"Repetitivo vai definir legalidade do ICMS sobre Tust e Tusd","datePublished":"2018-01-12T16:29:55+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/"},"wordCount":523,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"keywords":["Tribut\u00e1rio"],"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/","url":"https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/","name":"Repetitivo vai definir legalidade do ICMS sobre Tust e Tusd | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2018-01-12T16:29:55+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/repetitivo-vai-definir-legalidade-do-icms-sobre-tust-e-tusd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Repetitivo vai definir legalidade do ICMS sobre Tust e Tusd"}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161","url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/granda\/"}]}},"authors":[{"term_id":288,"user_id":2,"is_guest":0,"slug":"granda","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=1811"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1811\/revisions"}],"predecessor-version":[{"id":1812,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1811\/revisions\/1812"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=1811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=1811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=1811"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=1811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}