{"id":1786,"date":"2017-09-04T10:44:48","date_gmt":"2017-09-04T13:44:48","guid":{"rendered":"https:\/\/granda.com.br\/en\/?p=1786"},"modified":"2017-09-04T10:44:48","modified_gmt":"2017-09-04T13:44:48","slug":"receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/","title":{"rendered":"Receita Federal atualiza regras do Programa Especial de Regulariza\u00e7\u00e3o Tribut\u00e1ria (Pert)"},"content":{"rendered":"<p>Foi publicada no Di\u00e1rio Oficial da Uni\u00e3o a IN RFB n\u00ba 1733\/2017 que regulamenta a MP n\u00ba 798\/2017, a qual prorroga o prazo de ades\u00e3o ao Pert para o dia 29 de setembro.<\/p>\n<p>Para os contribuintes que efetuarem ades\u00e3o ao Pert no m\u00eas de setembro de 2017, as presta\u00e7\u00f5es venc\u00edveis no m\u00eas de agosto dever\u00e3o ser pagas cumulativamente com a presta\u00e7\u00e3o referente ao m\u00eas de setembro de 2017, conforme prev\u00ea a Medida Provis\u00f3ria n\u00ba 798, de 2017, como condi\u00e7\u00e3o de deferimento do parcelamento.<\/p>\n<p>Enquanto a d\u00edvida n\u00e3o for consolidada, o sujeito passivo dever\u00e1 calcular e recolher o valor \u00e0 vista ou o valor equivalente ao montante dos d\u00e9bitos objeto do parcelamento dividido pelo n\u00famero de presta\u00e7\u00f5es pretendidas.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: <a href=\"http:\/\/idg.receita.fazenda.gov.br\/noticias\/ascom\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\" target=\"_blank\" rel=\"noopener\">Receita Federal do Brasil<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi publicada no Di\u00e1rio Oficial da Uni\u00e3o a IN RFB n\u00ba 1733\/2017 que regulamenta a MP n\u00ba 798\/2017, a qual prorroga o prazo de ades\u00e3o ao Pert para o dia<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[61],"ppma_author":[288],"class_list":["post-1786","post","type-post","status-publish","format-standard","hentry","category-noticias-en","tag-tributario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Receita Federal atualiza regras do Programa Especial de Regulariza\u00e7\u00e3o Tribut\u00e1ria (Pert) | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Receita Federal atualiza regras do Programa Especial de Regulariza\u00e7\u00e3o Tribut\u00e1ria (Pert) | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-04T13:44:48+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\"},\"headline\":\"Receita Federal atualiza regras do Programa Especial de Regulariza\u00e7\u00e3o Tribut\u00e1ria (Pert)\",\"datePublished\":\"2017-09-04T13:44:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\\\/\"},\"wordCount\":146,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"keywords\":[\"Tribut\u00e1rio\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\\\/\",\"name\":\"Receita Federal atualiza regras do Programa Especial de Regulariza\u00e7\u00e3o Tribut\u00e1ria (Pert) | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2017-09-04T13:44:48+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Receita Federal atualiza regras do Programa Especial de Regulariza\u00e7\u00e3o Tribut\u00e1ria (Pert)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/granda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Receita Federal atualiza regras do Programa Especial de Regulariza\u00e7\u00e3o Tribut\u00e1ria (Pert) | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/","og_locale":"en_US","og_type":"article","og_title":"Receita Federal atualiza regras do Programa Especial de Regulariza\u00e7\u00e3o Tribut\u00e1ria (Pert) | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2017-09-04T13:44:48+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8"},"headline":"Receita Federal atualiza regras do Programa Especial de Regulariza\u00e7\u00e3o Tribut\u00e1ria (Pert)","datePublished":"2017-09-04T13:44:48+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/"},"wordCount":146,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"keywords":["Tribut\u00e1rio"],"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/","url":"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/","name":"Receita Federal atualiza regras do Programa Especial de Regulariza\u00e7\u00e3o Tribut\u00e1ria (Pert) | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2017-09-04T13:44:48+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/en\/receita-federal-atualiza-regras-do-programa-especial-de-regularizacao-tributaria-pert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Receita Federal atualiza regras do Programa Especial de Regulariza\u00e7\u00e3o Tribut\u00e1ria (Pert)"}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161","url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/granda\/"}]}},"authors":[{"term_id":288,"user_id":2,"is_guest":0,"slug":"granda","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=1786"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1786\/revisions"}],"predecessor-version":[{"id":1787,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1786\/revisions\/1787"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=1786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=1786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=1786"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=1786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}