{"id":1642,"date":"2017-02-15T09:19:10","date_gmt":"2017-02-15T11:19:10","guid":{"rendered":"https:\/\/granda.com.br\/en\/?p=1642"},"modified":"2017-02-15T09:19:10","modified_gmt":"2017-02-15T11:19:10","slug":"defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/","title":{"rendered":"Defeito em produto n\u00e3o gera indeniza\u00e7\u00e3o autom\u00e1tica por danos morais"},"content":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) rejeitou recurso que buscava condenar a Renault ao pagamento de indeniza\u00e7\u00e3o por danos morais em virtude de problema de solda em uma das colunas de um ve\u00edculo Renault Fluence.<\/p>\n<p>Para a ministra relatora do caso, Nancy Andrighi, o simples defeito t\u00e9cnico de um produto n\u00e3o \u00e9 capaz de gerar indeniza\u00e7\u00e3o por danos morais. Durante o julgamento, a ministra destacou a pertin\u00eancia da discuss\u00e3o sobre o tema, frequente no STJ. Para a magistrada, \u00e9 preciso estabelecer crit\u00e9rios espec\u00edficos para a condena\u00e7\u00e3o por danos morais.<\/p>\n<p>No voto, acompanhado pelos demais ministros da turma, Nancy Andrighi explicou que os danos morais correspondem a \u201cles\u00f5es a atributos da pessoa\u201d, algo mais profundo e contundente do que meros \u201cdissabores, desconfortos e frustra\u00e7\u00f5es de expectativas\u201d.<\/p>\n<p>A ministra lembrou que, apesar das regras dispostas no <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/Leis\/L8078.htm#art6\" target=\"_blank\" rel=\"noopener\"><strong>artigo 6\u00ba<\/strong><\/a> do C\u00f3digo de Defesa do Consumidor, \u201cn\u00e3o \u00e9 qualquer fato do produto ou do servi\u00e7o que enseja a indeniza\u00e7\u00e3o de danos morais\u201d.<\/p>\n<p><strong>Carro seguro<\/strong><\/p>\n<p>No recurso, o cliente alegou que comprou o ve\u00edculo justamente por ser um modelo seguro, e que a falha na solda da coluna em que o cinto de seguran\u00e7a \u00e9 fixado gerava risco \u00e0 sua vida. Por isso, seria justo ser indenizado, j\u00e1 que trafegava em rodovias todos os dias. Disse ter tentado resolver o problema em diversas ocasi\u00f5es, sempre sem sucesso.<\/p>\n<p>Segundo a ministra, n\u00e3o h\u00e1 comprova\u00e7\u00e3o de qual seria a consequ\u00eancia negativa para a personalidade do autor. \u201cDissabores, desgostos e frustra\u00e7\u00f5es comp\u00f5em muitas vezes a vida cotidiana e, nem por isso, s\u00e3o capazes de causar danos morais para aqueles que os suportam\u201d, concluiu.<\/p>\n<p><strong>Ilegitimidade<\/strong><\/p>\n<p>O caso foi julgado sem resolu\u00e7\u00e3o de m\u00e9rito em primeira e segunda inst\u00e2ncia devido \u00e0 ilegitimidade ativa do proponente da a\u00e7\u00e3o. O entendimento \u00e9 que mesmo sendo controlador da empresa, o particular n\u00e3o poderia ter ingressado com a a\u00e7\u00e3o, j\u00e1 que o carro foi adquirido por pessoa jur\u00eddica.<\/p>\n<p>A ministra relatora destacou que, independentemente da discuss\u00e3o sobre danos morais, o pleito do recorrente n\u00e3o teria sucesso, pois a jurisprud\u00eancia do STJ considera que, nesses casos, h\u00e1 ilegitimidade ativa do proponente, que n\u00e3o pode atuar como substituto processual na demanda.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.stj.jus.br\/sites\/STJ\/default\/pt_BR\/Comunica%C3%A7%C3%A3o\/noticias\/Not%C3%ADcias\/Defeito-em-produto-n%C3%A3o-gera-indeniza%C3%A7%C3%A3o-autom%C3%A1tica-por-danos-morais\" target=\"_blank\" rel=\"noopener\">Fonte: Superior Tribunal de Justi\u00e7a &#8211; STJ<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) rejeitou recurso que buscava condenar a Renault ao pagamento de indeniza\u00e7\u00e3o por danos morais em virtude de problema de solda em<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"ppma_author":[288],"class_list":["post-1642","post","type-post","status-publish","format-standard","hentry","category-noticias-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Defeito em produto n\u00e3o gera indeniza\u00e7\u00e3o autom\u00e1tica por danos morais | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Defeito em produto n\u00e3o gera indeniza\u00e7\u00e3o autom\u00e1tica por danos morais | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-15T11:19:10+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\"},\"headline\":\"Defeito em produto n\u00e3o gera indeniza\u00e7\u00e3o autom\u00e1tica por danos morais\",\"datePublished\":\"2017-02-15T11:19:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\\\/\"},\"wordCount\":409,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\\\/\",\"name\":\"Defeito em produto n\u00e3o gera indeniza\u00e7\u00e3o autom\u00e1tica por danos morais | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2017-02-15T11:19:10+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Defeito em produto n\u00e3o gera indeniza\u00e7\u00e3o autom\u00e1tica por danos morais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/granda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Defeito em produto n\u00e3o gera indeniza\u00e7\u00e3o autom\u00e1tica por danos morais | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/","og_locale":"en_US","og_type":"article","og_title":"Defeito em produto n\u00e3o gera indeniza\u00e7\u00e3o autom\u00e1tica por danos morais | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2017-02-15T11:19:10+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8"},"headline":"Defeito em produto n\u00e3o gera indeniza\u00e7\u00e3o autom\u00e1tica por danos morais","datePublished":"2017-02-15T11:19:10+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/"},"wordCount":409,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/","url":"https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/","name":"Defeito em produto n\u00e3o gera indeniza\u00e7\u00e3o autom\u00e1tica por danos morais | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2017-02-15T11:19:10+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/defeito-em-produto-nao-gera-indenizacao-automatica-por-danos-morais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Defeito em produto n\u00e3o gera indeniza\u00e7\u00e3o autom\u00e1tica por danos morais"}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161","url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/granda\/"}]}},"authors":[{"term_id":288,"user_id":2,"is_guest":0,"slug":"granda","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=1642"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1642\/revisions"}],"predecessor-version":[{"id":1643,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1642\/revisions\/1643"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=1642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=1642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=1642"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=1642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}