{"id":1622,"date":"2017-01-09T14:47:16","date_gmt":"2017-01-09T16:47:16","guid":{"rendered":"https:\/\/granda.com.br\/en\/?p=1622"},"modified":"2017-01-09T14:47:16","modified_gmt":"2017-01-09T16:47:16","slug":"medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/","title":{"rendered":"Medida Provis\u00f3ria 766\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT"},"content":{"rendered":"<p style=\"text-align: justify;\">Foi publicada a Medida Provis\u00f3ria 766\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT, o qual, diferente das edi\u00e7\u00f5es anteriores de REFIS, n\u00e3o traz redu\u00e7\u00f5es de multa e juros, apenas condi\u00e7\u00f5es diferenciadas de pagamento de d\u00e9bitos com a Receita Federal do Brasil e a Procuradoria Geral da Fazenda Nacional.<\/p>\n<p>A ades\u00e3o ao PRT dever\u00e1 ser realizada em at\u00e9 120 dias, contados da publica\u00e7\u00e3o da regulamenta\u00e7\u00e3o pela RFB e pela PGFN, as quais dever\u00e3o ser emitidas no prazo de 30 dias da publica\u00e7\u00e3o da MP.<\/p>\n<p>O referido programa permite a inclus\u00e3o de d\u00e9bitos <strong><em>(i)<\/em><\/strong> objeto de parcelamentos anteriores, rescindidos ou ativos, <strong><em>(ii)<\/em><\/strong> em discuss\u00e3o administrativa ou judicial, bem como <strong><em>(iii)<\/em><\/strong> oriundos de lan\u00e7amentos de of\u00edcio ocorridos ap\u00f3s a publica\u00e7\u00e3o da MP, desde que o requerimento seja realizado dentro do prazo, por\u00e9m veda a possibilidade de incluir os d\u00e9bitos que compor\u00e3o o PRT em qualquer outra forma de parcelamento posterior, com exce\u00e7\u00e3o do parcelamento da Lei 12.522\/02.<\/p>\n<p>Para d\u00e9bitos com a <strong>Receita Federal<\/strong>, o contribuinte poder\u00e1 optar por liquidar os d\u00e9bitos das seguintes formas:<\/p>\n<p>I &#8211; pagamento de, no m\u00ednimo, 20% \u00a0(vinte por cento) da d\u00edvida e liquida\u00e7\u00e3o do restante com a utiliza\u00e7\u00e3o de preju\u00edzo fiscal e base de c\u00e1lculo negativa da CSLL ou com outros cr\u00e9ditos pr\u00f3prios relativos aos tributos administrados pela Receita Federal do Brasil;<\/p>\n<p>II &#8211; pagamento de, no m\u00ednimo, 24% (vinte e quatro por cento) da d\u00edvida em 24 (vinte e quatro) presta\u00e7\u00f5es mensais e sucessivas e liquida\u00e7\u00e3o do restante com a utiliza\u00e7\u00e3o de cr\u00e9ditos de preju\u00edzo fiscal e base de c\u00e1lculo negativa da CSLL ou com outros cr\u00e9ditos pr\u00f3prios relativos aos tributos administrados pela Receita Federal do Brasil;<\/p>\n<p>III &#8211; pagamento de 20% (vinte por cento) da d\u00edvida e parcelamento do restante em at\u00e9 96 (noventa e seis) presta\u00e7\u00f5es mensais e sucessivas, e<\/p>\n<p>IV &#8211; pagamento da d\u00edvida consolidada em at\u00e9 120 (cento e vinte) presta\u00e7\u00f5es mensais e sucessivas, as quais dever\u00e3o ser calculadas observando os seguintes percentuais m\u00ednimos, aplicados sobre o valor da d\u00edvida consolidada:<\/p>\n<ol style=\"text-align: justify;\">\n<li>da primeira \u00e0 d\u00e9cima segunda presta\u00e7\u00e3o &#8211; 0,5% (cinco d\u00e9cimos por cento);<\/li>\n<li>da d\u00e9cima terceira \u00e0 vig\u00e9sima quarta presta\u00e7\u00e3o &#8211; 0,6% (seis d\u00e9cimos por cento);<\/li>\n<li>da vig\u00e9sima quinta \u00e0 trig\u00e9sima sexta presta\u00e7\u00e3o &#8211; 0,7% (sete d\u00e9cimos por cento); e<\/li>\n<li>da trig\u00e9sima s\u00e9tima presta\u00e7\u00e3o em diante &#8211; percentual correspondente ao saldo remanescente, em at\u00e9 84 (oitenta e quatro) presta\u00e7\u00f5es mensais e sucessivas<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Para as op\u00e7\u00f5es com utiliza\u00e7\u00e3o de cr\u00e9ditos oriundos de preju\u00edzos fiscais e bases negativas de CSLL poder\u00e3o ser utilizados aqueles apurados at\u00e9 31 de dezembro de 2015 e declarados at\u00e9 30 de junho de 2016 e, ap\u00f3s sua utiliza\u00e7\u00e3o, caso ainda haja saldo remanescente este poder\u00e1 ser parcelado em at\u00e9 60 (sessenta) presta\u00e7\u00f5es adicionais.<\/p>\n<p>No que se refere aos pagamentos de d\u00e9bitos no \u00e2mbito da <strong>Procuradoria Geral da Fazenda Nacional<\/strong>, o PRT oferece as seguintes formas de liquida\u00e7\u00e3o:<\/p>\n<p><strong>I &#8211;\u00a0<\/strong>pagamento \u00e0 vista de 20% \u00a0(vinte por cento) do valor da d\u00edvida consolidada e parcelamento do restante em at\u00e9 96 (noventa e seis) parcelas mensais e sucessivas; ou<\/p>\n<p><strong>II\u00a0<\/strong>&#8211; pagamento da d\u00edvida consolidada em at\u00e9 120 (cento e vinte) parcelas mensais e sucessivas, as quais dever\u00e3o ser calculadas observando os seguintes percentuais m\u00ednimos, aplicados sobre o valor da d\u00edvida consolidada:<\/p>\n<ol style=\"text-align: justify;\">\n<li>da primeira \u00e0 d\u00e9cima segunda presta\u00e7\u00e3o &#8211; 0,5% (cinco d\u00e9cimos por cento);<\/li>\n<li>da d\u00e9cima terceira \u00e0 vig\u00e9sima quarta presta\u00e7\u00e3o &#8211; 0,6% (seis d\u00e9cimos por cento);<\/li>\n<li>da vig\u00e9sima quinta \u00e0 trig\u00e9sima sexta presta\u00e7\u00e3o &#8211; 0,7% (sete d\u00e9cimos por cento); e<\/li>\n<li>a trig\u00e9sima s\u00e9tima presta\u00e7\u00e3o em diante &#8211; percentual correspondente ao saldo remanescente em at\u00e9 oitenta e quatro presta\u00e7\u00f5es mensais e sucessivas.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">As presta\u00e7\u00f5es n\u00e3o poder\u00e3o ser inferiores a R$200,00 para pessoa f\u00edsica e R$1.000,00 para pessoa jur\u00eddica.<\/p>\n<p style=\"text-align: justify;\">D\u00favida quanto ao novo Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria, estamos \u00e0 disposi\u00e7\u00e3o para lhes auxiliar!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi publicada a Medida Provis\u00f3ria 766\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT, o qual, diferente das edi\u00e7\u00f5es anteriores de REFIS, n\u00e3o traz redu\u00e7\u00f5es de multa e juros,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"ppma_author":[288],"class_list":["post-1622","post","type-post","status-publish","format-standard","hentry","category-noticias-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medida Provis\u00f3ria 766\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medida Provis\u00f3ria 766\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-09T16:47:16+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\"},\"headline\":\"Medida Provis\u00f3ria 766\\\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT\",\"datePublished\":\"2017-01-09T16:47:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\\\/\"},\"wordCount\":707,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\\\/\",\"name\":\"Medida Provis\u00f3ria 766\\\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2017-01-09T16:47:16+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medida Provis\u00f3ria 766\\\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/granda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medida Provis\u00f3ria 766\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/","og_locale":"en_US","og_type":"article","og_title":"Medida Provis\u00f3ria 766\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2017-01-09T16:47:16+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8"},"headline":"Medida Provis\u00f3ria 766\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT","datePublished":"2017-01-09T16:47:16+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/"},"wordCount":707,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/","url":"https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/","name":"Medida Provis\u00f3ria 766\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2017-01-09T16:47:16+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/medida-provisoria-7662017-que-instituiu-o-programa-de-regularizacao-tributaria-prt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Medida Provis\u00f3ria 766\/2017 que instituiu o Programa de Regulariza\u00e7\u00e3o Tribut\u00e1ria \u2013 PRT"}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161","url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/granda\/"}]}},"authors":[{"term_id":288,"user_id":2,"is_guest":0,"slug":"granda","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=1622"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1622\/revisions"}],"predecessor-version":[{"id":1623,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1622\/revisions\/1623"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=1622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=1622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=1622"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=1622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}