{"id":1617,"date":"2016-11-28T13:57:03","date_gmt":"2016-11-28T15:57:03","guid":{"rendered":"https:\/\/granda.com.br\/en\/?p=1617"},"modified":"2016-11-28T13:57:03","modified_gmt":"2016-11-28T15:57:03","slug":"adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/","title":{"rendered":"ADI questiona incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria sobre licen\u00e7a-maternidade"},"content":{"rendered":"<p style=\"text-align: justify;\">O procurador-geral da Rep\u00fablica, Rodrigo Janot, ajuizou no Supremo Tribunal Federal (STF) A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI 5626) contra dispositivos da Lei Org\u00e2nica da Seguridade Social (Lei 8.212\/1991) que fazem incidir a contribui\u00e7\u00e3o previdenci\u00e1ria sobre o sal\u00e1rio-maternidade. Segundo Janot, os par\u00e1grafos 2\u00ba e 9\u00ba (al\u00ednea \u201ca\u201d, parte final) do artigo 28 da lei s\u00e3o incompat\u00edveis com as garantias constitucionais de prote\u00e7\u00e3o \u00e0 maternidade e ao direito das mulheres de acesso ao mercado de trabalho.<\/p>\n<p style=\"text-align: justify;\">O procurador argumenta que as normas imputam ao empregador parte do \u00f4nus do afastamento da gestante devido \u00e0 maternidade e contribuem para o aumento do custo de sua m\u00e3o de obra, em compara\u00e7\u00e3o \u00e0 masculina. \u201cEssa condi\u00e7\u00e3o constitui significativo fator de discrimina\u00e7\u00e3o da mulher no mercado de trabalho\u201d, afirma.<\/p>\n<p style=\"text-align: justify;\">De acordo com a linha de argumenta\u00e7\u00e3o adotada na ADI, medidas estatais que imponham de forma desproporcional maior custo \u00e0 m\u00e3o de obra feminina s\u00e3o incompat\u00edveis com a premissa de equil\u00edbrio entre a prote\u00e7\u00e3o da maternidade e do emprego da mulher. Janot lembra que a Lei 6.136\/1974 transferiu \u00e0 Previd\u00eancia Social o encargo exclusivo pelo pagamento integral da remunera\u00e7\u00e3o da trabalhadora no per\u00edodo de licen\u00e7a, mas o empregador continuou obrigado a recolher a contribui\u00e7\u00e3o sobre o sal\u00e1rio-maternidade e, ainda, arcar com o encargo incidente sobre a remunera\u00e7\u00e3o de eventual trabalhador tempor\u00e1rio, substituto da licenciada. \u201cEssa dupla contribui\u00e7\u00e3o pelo mesmo posto de trabalho encarece a m\u00e3o de obra feminina e contraria a norma constitucional e a internacional\u201d, sustenta, referindo-se \u00e0 Conven\u00e7\u00e3o 103 da Organiza\u00e7\u00e3o Internacional do Trabalho.<\/p>\n<p style=\"text-align: justify;\">O procurador-geral pede, cautelarmente, a suspens\u00e3o da efic\u00e1cia das normas apontadas e, no m\u00e9rito, que o STF aplique a elas a t\u00e9cnica da interpreta\u00e7\u00e3o conforme a Constitui\u00e7\u00e3o para reconhecer ao sal\u00e1rio-maternidade a qualidade de sal\u00e1rio de contribui\u00e7\u00e3o apenas para fim de c\u00e1lculo de outros benef\u00edcios, afastando a incid\u00eancia direta da contribui\u00e7\u00e3o previdenci\u00e1ria linear a cargo do empregador.<\/p>\n<p style=\"text-align: justify;\">O relator da ADI 5626 \u00e9 o ministro Celso de Mello.<\/p>\n<p>&nbsp;<\/p>\n<h5><em><a href=\"http:\/\/www.stf.jus.br\/portal\/cms\/verNoticiaDetalhe.asp?idConteudo=330529\" target=\"_blank\" rel=\"noopener\">Fonte: Supremo Tribunal Federal &#8211; STF<\/a><\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>O procurador-geral da Rep\u00fablica, Rodrigo Janot, ajuizou no Supremo Tribunal Federal (STF) A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI 5626) contra dispositivos da Lei Org\u00e2nica da Seguridade Social (Lei 8.212\/1991) que fazem<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[131,172],"ppma_author":[288],"class_list":["post-1617","post","type-post","status-publish","format-standard","hentry","category-noticias-en","tag-stf","tag-tributario-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ADI questiona incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria sobre licen\u00e7a-maternidade | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ADI questiona incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria sobre licen\u00e7a-maternidade | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-28T15:57:03+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\"},\"headline\":\"ADI questiona incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria sobre licen\u00e7a-maternidade\",\"datePublished\":\"2016-11-28T15:57:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\\\/\"},\"wordCount\":368,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"keywords\":[\"STF\",\"Tribut\u00e1rio\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\\\/\",\"name\":\"ADI questiona incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria sobre licen\u00e7a-maternidade | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2016-11-28T15:57:03+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ADI questiona incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria sobre licen\u00e7a-maternidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/granda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ADI questiona incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria sobre licen\u00e7a-maternidade | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/","og_locale":"en_US","og_type":"article","og_title":"ADI questiona incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria sobre licen\u00e7a-maternidade | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2016-11-28T15:57:03+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8"},"headline":"ADI questiona incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria sobre licen\u00e7a-maternidade","datePublished":"2016-11-28T15:57:03+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/"},"wordCount":368,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"keywords":["STF","Tribut\u00e1rio"],"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/","url":"https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/","name":"ADI questiona incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria sobre licen\u00e7a-maternidade | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2016-11-28T15:57:03+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/adi-questiona-incidencia-da-contribuicao-previdenciaria-sobre-licenca-maternidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"ADI questiona incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria sobre licen\u00e7a-maternidade"}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161","url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/granda\/"}]}},"authors":[{"term_id":288,"user_id":2,"is_guest":0,"slug":"granda","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=1617"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1617\/revisions"}],"predecessor-version":[{"id":1618,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1617\/revisions\/1618"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=1617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=1617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=1617"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=1617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}