{"id":1547,"date":"2016-09-12T14:46:07","date_gmt":"2016-09-12T17:46:07","guid":{"rendered":"https:\/\/granda.com.br\/en\/?p=1547"},"modified":"2016-09-12T14:46:07","modified_gmt":"2016-09-12T17:46:07","slug":"ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/","title":{"rendered":"Ombudsman banc\u00e1rio \u00e9 alternativa \u00e0 sobrecarga do Judici\u00e1rio, diz Laurita Vaz (Presidente do STJ)"},"content":{"rendered":"<p>A busca pela resolu\u00e7\u00e3o extrajudicial dos conflitos oriundos das rela\u00e7\u00f5es de consumo \u00e9 oportuna e necess\u00e1ria. A avalia\u00e7\u00e3o foi feita pela presidente do Superior Tribunal de Justi\u00e7a (STJ), ministra Laurita Vaz, durante a abertura do<span class=\"Apple-converted-space\">\u00a0<\/span><em>I Semin\u00e1rio Ombudsman como Forma de Desjudicializa\u00e7\u00e3o dos Conflitos na Rela\u00e7\u00e3o de Consumo<\/em>, na manh\u00e3 desta segunda-feira (12).<\/p>\n<p>Realizado pelo STJ e pela FGV Projetos em parceria com a Federa\u00e7\u00e3o Brasileira de Bancos (Febraban) e o Instituto Brasiliense de Direito P\u00fablico (IDP), o semin\u00e1rio pretende construir uma base para a implanta\u00e7\u00e3o do servi\u00e7o de<span class=\"Apple-converted-space\">\u00a0<\/span><em>ombudsman<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>nos bancos brasileiros.<\/p>\n<p>As quest\u00f5es banc\u00e1rias respondem por quase 40% do movimento do judici\u00e1rio. Conforme a ministra presidente, \u201co direto do consumidor \u00e9 uma mat\u00e9ria afeta a toda pessoa que vive em sociedade\u201d. Laurita Vaz reconheceu que, diante da evidente sobrecarga de demanda, o Poder Judici\u00e1rio nem sempre entrega a presta\u00e7\u00e3o jurisdicional a contento. \u201cAcredito que os debates e as explana\u00e7\u00f5es apresentadas neste semin\u00e1rio ser\u00e3o de extrema relev\u00e2ncia\u201d, afirmou a ministra.<\/p>\n<p>O coordenador cient\u00edfico do semin\u00e1rio, ministro Villas B\u00f4as Cueva, levou aos participantes o preocupante dado do Conselho Nacional de Justi\u00e7a (CNJ) de que 1,3% do PIB \u00e9 gasto com o sistema de Justi\u00e7a no Brasil. Sufocado por demandas que n\u00e3o param de crescer, o sistema j\u00e1 acumula cem milh\u00f5es de processos em tramita\u00e7\u00e3o.<\/p>\n<p><strong>Modelo pr\u00f3prio<\/strong><\/p>\n<p>O semin\u00e1rio ir\u00e1 estabelecer contrastes entre alguns modelos de<span class=\"Apple-converted-space\">\u00a0<\/span><em>ombudsman<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>que existem no mundo, especialmente o alem\u00e3o e o ingl\u00eas. O ministro Cueva entende que o Brasil desenvolver\u00e1 um sistema pr\u00f3prio, a partir dos debates travados durante o evento. \u201cA ideia \u00e9 que tenhamos propostas concretas, no sentido de encontrarmos uma solu\u00e7\u00e3o para desjudicializa\u00e7\u00e3o dos conflitos de massa\u201d, resumiu.<\/p>\n<p>O ministro Luis Felipe Salom\u00e3o, conhecido por seu empenho na \u00e1rea da media\u00e7\u00e3o, comemorou a iniciativa. \u201cSe pudermos criar um mecanismo eficaz, que impe\u00e7a essas demandas repetitivas de atravancarem o Judici\u00e1rio, ser\u00e1 mais um passo no sentido da efici\u00eancia\u201d, declarou.<\/p>\n<p><strong>Cultura de judicializa\u00e7\u00e3o<\/strong><\/p>\n<p>O ministro Dias Toffoli, do Supremo Tribunal Federal (STF), destacou que a cultura de judicializa\u00e7\u00e3o no Brasil deve ser transformada desde a forma\u00e7\u00e3o do profissional de direito. Ele entende que os advogados t\u00eam papel fundamental no sucesso da ado\u00e7\u00e3o de m\u00e9todos alternativos de solu\u00e7\u00e3o de conflitos. \u201cExiste uma panaceia de que tudo tem que ir ao Judici\u00e1rio\u201d, afirmou.<\/p>\n<p>O diretor de rela\u00e7\u00f5es institucionais do Banco Central, Isaac Sidney Menezes Ferreira, opinou que a desjudicializa\u00e7\u00e3o pode contribuir para a redu\u00e7\u00e3o de custos e de riscos no Sistema Financeiro Nacional. Ele entende que a t\u00e3o almejada estabilidade econ\u00f4mica tamb\u00e9m pode ser diretamente beneficiada pela ado\u00e7\u00e3o de solu\u00e7\u00f5es alternativas nas disputas banc\u00e1rias.<\/p>\n<p>O presidente da C\u00e2mara dos Deputados, Rodrigo Maia, garantiu que a institui\u00e7\u00e3o estar\u00e1 sempre aberta a discutir propostas que modernizem a legisla\u00e7\u00e3o. Felipe Sarmento, representando a Ordem dos Advogados do Brasil, disse que processos longos n\u00e3o interessam a ningu\u00e9m, porque s\u00e3o caros para as partes e para a sociedade. Juliana Loss, coordenadora da FGV Media\u00e7\u00e3o, afirmou que a tarefa do semin\u00e1rio ser\u00e1 definir como o<span class=\"Apple-converted-space\">\u00a0<\/span><em>ombudsman<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>ser\u00e1 adotado no Brasil, propondo solu\u00e7\u00f5es concretas, ainda que n\u00e3o definitivas.<\/p>\n<p>Estiveram presentes \u00e0 abertura do evento o vice-presidente do STJ, ministro Humberto Martins, os ministros Paulo de Tarso Sanseverino, Moura Ribeiro, Gurgel de Faria e Sidnei Beneti (aposentado), entre outras autoridades.<\/p>\n<p><strong>Pain\u00e9is<\/strong><\/p>\n<p>Os pain\u00e9is discutir\u00e3o a figura do<span class=\"Apple-converted-space\">\u00a0<\/span><em>ombudsman<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>banc\u00e1rio na Alemanha e na Gr\u00e3-Bretanha, a import\u00e2ncia socioecon\u00f4mica da desjudicializa\u00e7\u00e3o dos conflitos de consumo, os elementos que levam \u00e0 judicializa\u00e7\u00e3o no Brasil e as experi\u00eancias contempor\u00e2neas para a resolu\u00e7\u00e3o de disputas. Tamb\u00e9m ser\u00e1 elaborada uma proposta de autorregula\u00e7\u00e3o do<span class=\"Apple-converted-space\">\u00a0<\/span><em>ombudsman<\/em><span class=\"Apple-converted-space\">\u00a0<\/span>para o setor banc\u00e1rio. O semin\u00e1rio \u00e9 aberto ao p\u00fablico e acontece no audit\u00f3rio externo do STJ, em Bras\u00edlia. O encerramento ser\u00e1 amanh\u00e3, ter\u00e7a-feira (13), \u00e0s 18h.<\/p>\n<p>&nbsp;<\/p>\n<h5><a href=\"http:\/\/www.stj.jus.br\/sites\/STJ\/default\/pt_BR\/Comunica%C3%A7%C3%A3o\/Not%C3%ADcias\/Not%C3%ADcias\/Ombudsman-banc%C3%A1rio-%C3%A9-alternativa-%C3%A0-sobrecarga-do-Judici%C3%A1rio,-diz-Laurita-Vaz\" target=\"_blank\" rel=\"noopener\"><em>Fonte: Superior Tribunal de Justi\u00e7a<\/em><\/a><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>A busca pela resolu\u00e7\u00e3o extrajudicial dos conflitos oriundos das rela\u00e7\u00f5es de consumo \u00e9 oportuna e necess\u00e1ria. A avalia\u00e7\u00e3o foi feita pela presidente do Superior Tribunal de Justi\u00e7a (STJ), ministra Laurita<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"ppma_author":[288],"class_list":["post-1547","post","type-post","status-publish","format-standard","hentry","category-noticias-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ombudsman banc\u00e1rio \u00e9 alternativa \u00e0 sobrecarga do Judici\u00e1rio, diz Laurita Vaz (Presidente do STJ) | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ombudsman banc\u00e1rio \u00e9 alternativa \u00e0 sobrecarga do Judici\u00e1rio, diz Laurita Vaz (Presidente do STJ) | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-12T17:46:07+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\"},\"headline\":\"Ombudsman banc\u00e1rio \u00e9 alternativa \u00e0 sobrecarga do Judici\u00e1rio, diz Laurita Vaz (Presidente do STJ)\",\"datePublished\":\"2016-09-12T17:46:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\\\/\"},\"wordCount\":711,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\\\/\",\"name\":\"Ombudsman banc\u00e1rio \u00e9 alternativa \u00e0 sobrecarga do Judici\u00e1rio, diz Laurita Vaz (Presidente do STJ) | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2016-09-12T17:46:07+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ombudsman banc\u00e1rio \u00e9 alternativa \u00e0 sobrecarga do Judici\u00e1rio, diz Laurita Vaz (Presidente do STJ)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/granda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ombudsman banc\u00e1rio \u00e9 alternativa \u00e0 sobrecarga do Judici\u00e1rio, diz Laurita Vaz (Presidente do STJ) | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/","og_locale":"en_US","og_type":"article","og_title":"Ombudsman banc\u00e1rio \u00e9 alternativa \u00e0 sobrecarga do Judici\u00e1rio, diz Laurita Vaz (Presidente do STJ) | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2016-09-12T17:46:07+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8"},"headline":"Ombudsman banc\u00e1rio \u00e9 alternativa \u00e0 sobrecarga do Judici\u00e1rio, diz Laurita Vaz (Presidente do STJ)","datePublished":"2016-09-12T17:46:07+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/"},"wordCount":711,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/","url":"https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/","name":"Ombudsman banc\u00e1rio \u00e9 alternativa \u00e0 sobrecarga do Judici\u00e1rio, diz Laurita Vaz (Presidente do STJ) | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2016-09-12T17:46:07+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/ombudsman-bancario-e-alternativa-sobrecarga-do-judiciario-diz-laurita-vaz-presidente-do-stj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Ombudsman banc\u00e1rio \u00e9 alternativa \u00e0 sobrecarga do Judici\u00e1rio, diz Laurita Vaz (Presidente do STJ)"}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161","url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/granda\/"}]}},"authors":[{"term_id":288,"user_id":2,"is_guest":0,"slug":"granda","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=1547"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1547\/revisions"}],"predecessor-version":[{"id":1548,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1547\/revisions\/1548"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=1547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=1547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=1547"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=1547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}