{"id":1181,"date":"2016-06-10T14:24:03","date_gmt":"2016-06-10T14:24:03","guid":{"rendered":"http:\/\/3wmarketing.com.br\/Clientes\/Granda\/Site\/Modelo01\/en\/blog\/2016\/06\/10\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/"},"modified":"2016-06-18T18:35:02","modified_gmt":"2016-06-18T21:35:02","slug":"receita-altera-normas-relativas-a-dctf-e-a-dspj","status":"publish","type":"post","link":"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/","title":{"rendered":"Receita altera normas relativas \u00e0 DCTF e \u00e0 DSPJ"},"content":{"rendered":"<h5><em><span class=\"post-meta-key\">Fonte:<\/span> Site da Receita Federal do Brasil<\/em><\/h5>\n<p>&nbsp;<\/p>\n<p>Com as altera\u00e7\u00f5es trazidas pela IN RFB 1.646, publicada no Di\u00e1rio Oficial da Uni\u00e3o, as pessoas jur\u00eddicas inativas dever\u00e3o apresentar Declara\u00e7\u00e3o de D\u00e9bitos e Cr\u00e9ditos Tribut\u00e1rios Federais &#8211; DCTF relativa a janeiro de cada ano-calend\u00e1rio, obriga\u00e7\u00e3o que j\u00e1 era exigida para as pessoas jur\u00eddicas que n\u00e3o possuem d\u00e9bitos a declarar.<\/p>\n<p>Excepcionalmente para este ano-calend\u00e1rio, as pessoas jur\u00eddicas inativas dever\u00e3o apresentar a DCTF relativa a janeiro de 2016 no dia 21\/7\/2016, ainda que neste ano tenham apresentado a Declara\u00e7\u00e3o Simplificada da Pessoa Jur\u00eddica &#8211; DSPJ &#8211; Inativa 2016. Tamb\u00e9m ser\u00e1 permitida a entrega da DCTF de janeiro de 2016 sem a utiliza\u00e7\u00e3o de certificado digital pelas empresas inativas que tenham apresentado a DSPJ &#8211; Inativa 2016.<\/p>\n<p>Atualmente, a DCTF tamb\u00e9m \u00e9 utilizada para presta\u00e7\u00e3o de informa\u00e7\u00f5es relativas \u00e0 extin\u00e7\u00e3o, incorpora\u00e7\u00e3o, fus\u00e3o ou cis\u00e3o parcial ou total pelas pessoas jur\u00eddicas inativas. Como essas informa\u00e7\u00f5es tamb\u00e9m s\u00e3o exigidas na DSPJ &#8211; Inativa 2016, a partir de 31\/5\/2016 a presta\u00e7\u00e3o dessas informa\u00e7\u00f5es passar\u00e1 a ser realizada somente na DCTF e a DSPJ &#8211; Inativa 2016, nessas situa\u00e7\u00f5es, n\u00e3o ser\u00e1 mais aceita. A partir do ano-calend\u00e1rio de 2017 todas as informa\u00e7\u00f5es relativas \u00e0 inatividade dever\u00e3o ser informadas apenas na DCTF.<\/p>\n<p>A IN da DCTF tamb\u00e9m est\u00e1 sendo alterada para esclarecer que as empresas enquadradas no Simples Nacional e sujeitas \u00e0 Contribui\u00e7\u00e3o Previdenci\u00e1ria sobre a Receita Bruta (CPRB) somente devem apresentar DCTF relativa \u00e0s compet\u00eancias em que houver valor de CPRB a informar, e nesse caso, dever\u00e3o declarar tamb\u00e9m os valores dos impostos e contribui\u00e7\u00f5es n\u00e3o abarcados pelo recolhimento unificado do Simples Nacional, devidos na qualidade de contribuinte ou respons\u00e1vel.<\/p>\n<p>Outra altera\u00e7\u00e3o trata da inclus\u00e3o de c\u00f3digos de receita relativos \u00e0 reten\u00e7\u00e3o de Imposto de Renda incidente sobre rendimentos pagos pelos Estados, pelo Distrito Federal e pelos Munic\u00edpios, bem como por suas autarquias e funda\u00e7\u00f5es, a pessoas f\u00edsicas em decorr\u00eancia de contrato de trabalho, na rela\u00e7\u00e3o de c\u00f3digos cujos valores est\u00e3o dispensados de serem informados na DCTF. Para as demais situa\u00e7\u00f5es, ocorrendo a reten\u00e7\u00e3o de Imposto de Renda na fonte, esses entes e entidades devem declarar tais valores \u00e0 Receita Federal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Site da Receita Federal do Brasil &nbsp; Com as altera\u00e7\u00f5es trazidas pela IN RFB 1.646, publicada no Di\u00e1rio Oficial da Uni\u00e3o, as pessoas jur\u00eddicas inativas dever\u00e3o apresentar Declara\u00e7\u00e3o de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"ppma_author":[288],"class_list":["post-1181","post","type-post","status-publish","format-standard","hentry","category-noticias-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Receita altera normas relativas \u00e0 DCTF e \u00e0 DSPJ | Granda Advogados<\/title>\n<meta name=\"description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Receita altera normas relativas \u00e0 DCTF e \u00e0 DSPJ | Granda Advogados\" \/>\n<meta property=\"og:description\" content=\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/\" \/>\n<meta property=\"og:site_name\" content=\"Granda Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-10T14:24:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-18T21:35:02+00:00\" \/>\n<meta name=\"author\" content=\"Granda Advogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:site\" content=\"@GrandaAdvogados\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Granda Advogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-altera-normas-relativas-a-dctf-e-a-dspj\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-altera-normas-relativas-a-dctf-e-a-dspj\\\/\"},\"author\":{\"name\":\"Granda Advogados\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\"},\"headline\":\"Receita altera normas relativas \u00e0 DCTF e \u00e0 DSPJ\",\"datePublished\":\"2016-06-10T14:24:03+00:00\",\"dateModified\":\"2016-06-18T21:35:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-altera-normas-relativas-a-dctf-e-a-dspj\\\/\"},\"wordCount\":405,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-altera-normas-relativas-a-dctf-e-a-dspj\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-altera-normas-relativas-a-dctf-e-a-dspj\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-altera-normas-relativas-a-dctf-e-a-dspj\\\/\",\"name\":\"Receita altera normas relativas \u00e0 DCTF e \u00e0 DSPJ | Granda Advogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\"},\"datePublished\":\"2016-06-10T14:24:03+00:00\",\"dateModified\":\"2016-06-18T21:35:02+00:00\",\"description\":\"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-altera-normas-relativas-a-dctf-e-a-dspj\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-altera-normas-relativas-a-dctf-e-a-dspj\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/en\\\/receita-altera-normas-relativas-a-dctf-e-a-dspj\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/granda.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Receita altera normas relativas \u00e0 DCTF e \u00e0 DSPJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#website\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"name\":\"Granda Advogados\",\"description\":\"Assessoria Jur\u00eddica, Direito Empresarial\",\"publisher\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granda.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#organization\",\"name\":\"Granda Advogados\",\"url\":\"https:\\\/\\\/granda.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"contentUrl\":\"https:\\\/\\\/granda.com.br\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Logo_Granda_Advogados.png\",\"width\":264,\"height\":266,\"caption\":\"Granda Advogados\"},\"image\":{\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Granda-Advogados-215807355224688\\\/\",\"https:\\\/\\\/x.com\\\/GrandaAdvogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/granda-advogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granda.com.br\\\/#\\\/schema\\\/person\\\/cda467b86bab83c2015222593d428fb8\",\"name\":\"Granda Advogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g\",\"caption\":\"Granda Advogados\"},\"url\":\"https:\\\/\\\/granda.com.br\\\/en\\\/author\\\/granda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Receita altera normas relativas \u00e0 DCTF e \u00e0 DSPJ | Granda Advogados","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/","og_locale":"en_US","og_type":"article","og_title":"Receita altera normas relativas \u00e0 DCTF e \u00e0 DSPJ | Granda Advogados","og_description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","og_url":"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/","og_site_name":"Granda Advogados","article_publisher":"https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","article_published_time":"2016-06-10T14:24:03+00:00","article_modified_time":"2016-06-18T21:35:02+00:00","author":"Granda Advogados","twitter_card":"summary_large_image","twitter_creator":"@GrandaAdvogados","twitter_site":"@GrandaAdvogados","twitter_misc":{"Written by":"Granda Advogados","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/#article","isPartOf":{"@id":"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/"},"author":{"name":"Granda Advogados","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8"},"headline":"Receita altera normas relativas \u00e0 DCTF e \u00e0 DSPJ","datePublished":"2016-06-10T14:24:03+00:00","dateModified":"2016-06-18T21:35:02+00:00","mainEntityOfPage":{"@id":"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/"},"wordCount":405,"commentCount":0,"publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/","url":"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/","name":"Receita altera normas relativas \u00e0 DCTF e \u00e0 DSPJ | Granda Advogados","isPartOf":{"@id":"https:\/\/granda.com.br\/#website"},"datePublished":"2016-06-10T14:24:03+00:00","dateModified":"2016-06-18T21:35:02+00:00","description":"Granda Advogados oferece assessoria jur\u00eddica multidisciplinar, consultiva e contenciosa, nas diversas \u00e1reas do Direito Empresarial.","breadcrumb":{"@id":"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/granda.com.br\/en\/receita-altera-normas-relativas-a-dctf-e-a-dspj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/granda.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Receita altera normas relativas \u00e0 DCTF e \u00e0 DSPJ"}]},{"@type":"WebSite","@id":"https:\/\/granda.com.br\/#website","url":"https:\/\/granda.com.br\/","name":"Granda Advogados","description":"Assessoria Jur\u00eddica, Direito Empresarial","publisher":{"@id":"https:\/\/granda.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granda.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/granda.com.br\/#organization","name":"Granda Advogados","url":"https:\/\/granda.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","contentUrl":"https:\/\/granda.com.br\/wp-content\/uploads\/2016\/06\/Logo_Granda_Advogados.png","width":264,"height":266,"caption":"Granda Advogados"},"image":{"@id":"https:\/\/granda.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Granda-Advogados-215807355224688\/","https:\/\/x.com\/GrandaAdvogados","https:\/\/www.linkedin.com\/company\/granda-advogados"]},{"@type":"Person","@id":"https:\/\/granda.com.br\/#\/schema\/person\/cda467b86bab83c2015222593d428fb8","name":"Granda Advogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g8110c9436d291901877db0feb49ac161","url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","caption":"Granda Advogados"},"url":"https:\/\/granda.com.br\/en\/author\/granda\/"}]}},"authors":[{"term_id":288,"user_id":2,"is_guest":0,"slug":"granda","display_name":"Granda Advogados","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48a0d3a541c8d35075574c08716c7dbfb7dd434eed1ce9478c45ac7c4f8d6d92?s=96&d=mm&r=g","author_category":"","first_name":"Granda","last_name":"Advogados","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/comments?post=1181"}],"version-history":[{"count":1,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1181\/revisions"}],"predecessor-version":[{"id":1185,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/posts\/1181\/revisions\/1185"}],"wp:attachment":[{"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/media?parent=1181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/categories?post=1181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/tags?post=1181"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/granda.com.br\/en\/wp-json\/wp\/v2\/ppma_author?post=1181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}